{"id":230,"count":1,"description":"","link":"https:\/\/jmrealestatezante.com\/de\/property_area\/xygia-de\/","name":"Xygia","slug":"xygia-de","taxonomy":"property_area","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/jmrealestatezante.com\/de\/property_area\/xygia-de\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/wp-json\\\/wp\\\/v2\\\/property_area\\\/230\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/property_area\\\/xygia-de\\\/#listItem\",\"name\":\"Xygia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/property_area\\\/xygia-de\\\/#listItem\",\"position\":2,\"name\":\"Xygia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/wp-json\\\/wp\\\/v2\\\/property_area\\\/230\\\/#collectionpage\",\"url\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/wp-json\\\/wp\\\/v2\\\/property_area\\\/230\\\/\",\"name\":\"Xygia - JM Real Estate\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/wp-json\\\/wp\\\/v2\\\/property_area\\\/230\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/#organization\",\"name\":\"JM Real Estate\",\"url\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/\",\"name\":\"JM Real Estate\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/jmrealestatezante.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Xygia - JM Real Estate","description":"","canonical_url":"https:\/\/jmrealestatezante.com\/de\/property_area\/xygia-de\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/property_area\/230\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/jmrealestatezante.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/jmrealestatezante.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/jmrealestatezante.com\/de\/property_area\/xygia-de\/#listItem","name":"Xygia"}},{"@type":"ListItem","@id":"https:\/\/jmrealestatezante.com\/de\/property_area\/xygia-de\/#listItem","position":2,"name":"Xygia","previousItem":{"@type":"ListItem","@id":"https:\/\/jmrealestatezante.com\/de\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/property_area\/230\/#collectionpage","url":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/property_area\/230\/","name":"Xygia - JM Real Estate","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/jmrealestatezante.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/property_area\/230\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/jmrealestatezante.com\/de\/#organization","name":"JM Real Estate","url":"https:\/\/jmrealestatezante.com\/de\/"},{"@type":"WebSite","@id":"https:\/\/jmrealestatezante.com\/de\/#website","url":"https:\/\/jmrealestatezante.com\/de\/","name":"JM Real Estate","inLanguage":"de-DE","publisher":{"@id":"https:\/\/jmrealestatezante.com\/de\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/jmrealestatezante.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tXygia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/jmrealestatezante.com\/de\/"},{"label":"Xygia","link":"https:\/\/jmrealestatezante.com\/de\/property_area\/xygia-de\/"}],"_links":{"self":[{"href":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/property_area\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/property_area"}],"about":[{"href":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/taxonomies\/property_area"}],"wp:post_type":[{"href":"https:\/\/jmrealestatezante.com\/de\/wp-json\/wp\/v2\/estate_property?property_area=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}